{"id":2172,"date":"2020-09-23T00:00:00","date_gmt":"2020-09-23T00:00:00","guid":{"rendered":"https:\/\/equipvinyesdabad.com\/?p=2172"},"modified":"2024-10-22T08:51:07","modified_gmt":"2024-10-22T08:51:07","slug":"vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open","status":"publish","type":"post","link":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/","title":{"rendered":"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-size: medium;\"><strong>El equipo Baporo Motorsport se desplazar&aacute; al Aut&oacute;dromo de Monza para disputar el tercer meeting del certamen europeo de GTs<\/strong> <\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Joan VInyes debutar&aacute; la presente temporada en el GT Cup Open Europe en la tercera cita de su calendario, precisamente el meeting que se correr&aacute; los pr&oacute;ximos d&iacute;as ( 25, 26 y 27) en un escenario m&iacute;tico del automovilismo mundial, el Aut&oacute;dromo de Monza. Vinyes, que compartir&aacute; el volante del Porsche GT3 &#8211; Baporo Motorsport con Jaume Font, intentar&aacute;n repetir el doble triunfo del pasado fin de semana, en la prueba del CER disputada en el trazado de Jerez.&nbsp; &nbsp;<\/p>\n<p><strong>Un escenario en el que Vinyes no ha competido desde el 2006.<\/strong><br \/>El circuito de la Lombardia, se empez&oacute; a construir en el 1922 y tiene como principal caracter&iacute;stica las altas velocidades que se alcanzan en las largas rectas del trazado. Son casi 6 km, de recorrido que las mec&aacute;nicas del GT Cup Open, la temporada 2019, completaron en menos de 2&rsquo;, a promedios superiores a los 180 km7h.<\/p>\n<p>La temporada pasada Vinyes no pudo competir en Monza, por problemas de agenda. En la presente edici&oacute;n, 14 a&ntilde;os despu&eacute;s, volver&aacute; a competir en el asfalto italiano. As&iacute; lo comentaba: <em><strong>Competir en Monza o en alguno de los trazados m&iacute;ticos, siempre es una motivaci&oacute;n extra. Es cierto que hace muchos a&ntilde;os que no compito en Monza, ser&aacute; como empezar de cero, el recuerdo de la &uacute;ltima vez tampoco fue muy positivo. Espero tener m&aacute;s suerte esta vez, comenzaremos a trabajar en el Porsche desde el minuto 1 de los primeros libres.<\/strong><\/em><\/p>\n<p><strong>Los libres previos al meeting, m&aacute;s necesarios que nunca.<\/strong><br \/>Vinyes iniciar&aacute; su actividad en el trazado italiano con la disputa de los entrenamientos libres que los organizadores, GT Sport Organisation, han programado para el jueves (d&iacute;a 24). Ser&aacute;n dos series de 60&rsquo; cada una en la que los equipos que lo deseen podr&aacute;n empezar a preparar sus mec&aacute;nicas de cara al meeting posterior.<\/p>\n<p>A lo largo de la jornada siguiente, viernes (d&iacute;a 25), empezar&aacute; la disputa de las mangas del meeting. En concreto durante esta primera jornada los equipos podr&aacute;n probar de manera indistinta con cada uno de sus pilotos, durante dos series de 50&rsquo;.<\/p>\n<p>El crono se pondr&aacute; en marcha, de manera oficial, el s&aacute;bado (d&iacute;a 26). Los entrenamientos oficiales del piloto 1 y la primera carrera, centrar&aacute;n la atenci&oacute;n de los equipos. El meeting se cerrar&aacute; el domingo con la disputa de los entrenamientos del piloto 2 y la segunda carrera.&nbsp; &nbsp;<\/p>\n<p>Las gradas del trazado del norte de MIlan, normalmente llenas de tifosi, en esta ocasi&oacute;n estar&aacute;n en silencio. El meeting del GT Cup Open Europe se disputar&aacute; siguiendo las estrictas medidas de seguridad a las que est&aacute;n sometidos, en estos momentos, los eventos de todo tipo.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: x-small;\"><strong><strong><strong><strong><a href=\"http:\/\/www.infoesport.org\/imgNoticia\/2020\/200927ViMonza1c.pdf\"><img loading=\"lazy\" decoding=\"async\" style=\"float: right;\" src=\"http:\/\/www.infoesport.org\/auxiliar\/fot\/logos\/icono_pdf.gif\" alt=\"\" width=\"50\" height=\"50\" \/><\/a><\/strong><\/strong><\/strong><\/strong><\/span><\/p>\n<p style=\"text-align: right;\">Servicio de prensa.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo Baporo Motorsport se desplazar\u00e1 al Aut\u00f3dromo de Monza para disputar el tercer meeting del certamen europeo de GTs <\/p>\n","protected":false},"author":1,"featured_media":1548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[52,50],"tags":[],"class_list":["post-2172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-circuitos","category-circuits"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open - Equip vinyes dabad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open - Equip vinyes dabad\" \/>\n<meta property=\"og:description\" content=\"El equipo Baporo Motorsport se desplazar\u00e1 al Aut\u00f3dromo de Monza para disputar el tercer meeting del certamen europeo de GTs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/\" \/>\n<meta property=\"og:site_name\" content=\"Equip vinyes dabad\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-23T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T08:51:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2024\/10\/logo_vinyes_dabad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"130\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#\\\/schema\\\/person\\\/962b4c681d63fd4fbd546ec83b775c1b\"},\"headline\":\"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open\",\"datePublished\":\"2020-09-23T00:00:00+00:00\",\"dateModified\":\"2024-10-22T08:51:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/\"},\"wordCount\":539,\"image\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equipvinyesdabad.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20105ViJerez9893.jpg\",\"articleSection\":[\"Circuitos\",\"Circuits\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/\",\"url\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/\",\"name\":\"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open - Equip vinyes dabad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equipvinyesdabad.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20105ViJerez9893.jpg\",\"datePublished\":\"2020-09-23T00:00:00+00:00\",\"dateModified\":\"2024-10-22T08:51:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#\\\/schema\\\/person\\\/962b4c681d63fd4fbd546ec83b775c1b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equipvinyesdabad.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20105ViJerez9893.jpg\",\"contentUrl\":\"https:\\\/\\\/equipvinyesdabad.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/20105ViJerez9893.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuits\\\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/\",\"name\":\"Equip vinyes dabad\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#\\\/schema\\\/person\\\/962b4c681d63fd4fbd546ec83b775c1b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/equipvinyesdabad.com\"],\"url\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/author\\\/web1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open - Equip vinyes dabad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/","og_locale":"es_ES","og_type":"article","og_title":"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open - Equip vinyes dabad","og_description":"El equipo Baporo Motorsport se desplazar\u00e1 al Aut\u00f3dromo de Monza para disputar el tercer meeting del certamen europeo de GTs","og_url":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/","og_site_name":"Equip vinyes dabad","article_published_time":"2020-09-23T00:00:00+00:00","article_modified_time":"2024-10-22T08:51:07+00:00","og_image":[{"width":250,"height":130,"url":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2024\/10\/logo_vinyes_dabad.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/#article","isPartOf":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/"},"author":{"name":"admin","@id":"https:\/\/equipvinyesdabad.com\/es\/#\/schema\/person\/962b4c681d63fd4fbd546ec83b775c1b"},"headline":"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open","datePublished":"2020-09-23T00:00:00+00:00","dateModified":"2024-10-22T08:51:07+00:00","mainEntityOfPage":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/"},"wordCount":539,"image":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/#primaryimage"},"thumbnailUrl":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2020\/09\/20105ViJerez9893.jpg","articleSection":["Circuitos","Circuits"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/","url":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/","name":"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open - Equip vinyes dabad","isPartOf":{"@id":"https:\/\/equipvinyesdabad.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/#primaryimage"},"image":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/#primaryimage"},"thumbnailUrl":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2020\/09\/20105ViJerez9893.jpg","datePublished":"2020-09-23T00:00:00+00:00","dateModified":"2024-10-22T08:51:07+00:00","author":{"@id":"https:\/\/equipvinyesdabad.com\/es\/#\/schema\/person\/962b4c681d63fd4fbd546ec83b775c1b"},"breadcrumb":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/#primaryimage","url":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2020\/09\/20105ViJerez9893.jpg","contentUrl":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2020\/09\/20105ViJerez9893.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/equipvinyesdabad.com\/es\/circuits\/vinyes-font-porsche-gt3-no-faltaran-a-la-cita-italiana-del-gt-cup-open\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/equipvinyesdabad.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vinyes-Font (Porsche GT3) no faltar\u00e1n a la cita italiana del GT Cup Open"}]},{"@type":"WebSite","@id":"https:\/\/equipvinyesdabad.com\/es\/#website","url":"https:\/\/equipvinyesdabad.com\/es\/","name":"Equip vinyes dabad","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equipvinyesdabad.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/equipvinyesdabad.com\/es\/#\/schema\/person\/962b4c681d63fd4fbd546ec83b775c1b","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/equipvinyesdabad.com"],"url":"https:\/\/equipvinyesdabad.com\/es\/author\/web1\/"}]}},"_links":{"self":[{"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/posts\/2172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/comments?post=2172"}],"version-history":[{"count":3,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/posts\/2172\/revisions"}],"predecessor-version":[{"id":4052,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/posts\/2172\/revisions\/4052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/media\/1548"}],"wp:attachment":[{"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/media?parent=2172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/categories?post=2172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/tags?post=2172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}