{"id":2441,"date":"2016-06-21T00:00:00","date_gmt":"2016-06-21T00:00:00","guid":{"rendered":"https:\/\/equipvinyesdabad.com\/?p=2441"},"modified":"2024-10-31T20:22:38","modified_gmt":"2024-10-31T20:22:38","slug":"motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir","status":"publish","type":"post","link":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/","title":{"rendered":"Motorland el escenario escogido por Joan Vinyes para volver a competir"},"content":{"rendered":"<p style=\"text-align: justify;\">Joan Vinyes, al volante de un Seat Le&oacute;n preparado por Baporo Motorsport, estar&aacute; en la pista de las instalaciones de Motorland para disputar las pruebas del Campeonato de Espa&ntilde;a de Resistencia programadas en el tercer meeting del calendario 2016 del mencionado certamen. En la cita de Alca&ntilde;iz, Vinyes compartir&aacute; el volante del Le&oacute;n con Marc Carol.&nbsp; &nbsp;<\/p>\n<p>Despu&eacute;s de su primera aparici&oacute;n, esta temporada, en el Circuito de Barcelona &#8211; Catalu&ntilde;a, Joan no ha tenido ocasi&oacute;n de volver a correr a pesar de mantener la motivaci&oacute;n intacta para seguir compitiendo, Este era su comentario respecto al exigente meeting de Motorland: <em><strong>Es cierto que estoy al 110 % de motivaci&oacute;n a pesar de que f&iacute;sicamente a&uacute;n me falta un poco para decir que estoy plenamente recuperado. Sigo con la intenci&oacute;n de hacer kil&oacute;metros y el CER de Alca&ntilde;iz es una ocasi&oacute;n inmejorable. A parte de las habituales series de entrenamientos habr&aacute; dos carreras de resistencia y esto quiere decir mucho tiempo en la pista para recuperar las mejores sensaciones.<\/strong><\/em><br \/>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<br \/>El objetivo de campe&oacute;n andorrano es completar sus relevos en las dos carreras programadas, as&iacute; nos lo contaba: <em><strong>En el programa del fin de semana hay dos pruebas v&aacute;lidas para los Campeonatos de Espa&ntilde;a de Resistencia. La del s&aacute;bado y la primera hora de la del domingo para el CER GT, y las tres horas completas del domingo para el CER LD. A pesar de no seguir, a priori, ninguno de los dos campeonatos, disputaremos las dos carreras. Ser&aacute; un excelente test para mi estado f&iacute;sico y para recuperar ritmo de competici&oacute;n.<\/strong><\/em><\/p>\n<p>En la pista de la provincia de Teruel, bien conocida tanto por Vinyes como por Carol, uno de los elementos a batir ser&aacute; el calor que, sobre todo en la prueba de 3 horas que cerrar&aacute; el programa del meeting organizado por Vline Organizaci&oacute;n.&nbsp; &nbsp;<\/p>\n<p>Para el t&aacute;ndem Joan Vinyes &#8211; Marc Carol y su equipo (Baporo Motorsport), la actividad en la pista se iniciar&aacute; el s&aacute;bado (d&iacute;a 25) a partir de las 10.20 h, momento en el que comenzar&aacute; la primera manga de entrenamientos privados. Esta primera jornada ser&aacute; especialmente densa, los equipos permanecer&aacute;n mas de 12 horas en las instalaciones de Motorland.<br \/>Para el domingo (d&iacute;a 26) a partir de las 10.55 h, quedar&aacute; la carrera del CER LD como cierre del meeting que da paso al periodo de vacaciones para los equipos habituales en estos campeonatos. &nbsp;<\/p>\n<p><\/p>\n<p style=\"text-align: right;\"><strong><a href=\"http:\/\/www.infoesport.org\/imgNoticia\/2016\/160626JVAlc1c.pdf\"><img loading=\"lazy\" decoding=\"async\" style=\"float: right;\" src=\"http:\/\/www.infoesport.org\/auxiliar\/fot\/logos\/icono_pdf.gif\" alt=\"\" width=\"50\" height=\"50\" \/><\/a><\/strong>Servicio de prensa.<\/p>\n<p><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: medium;\"><strong>Horarios CER \/ Circuito de Motorland &#8211; Alca&ntilde;iz.<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.infoesport.org\/auxiliar\/Horaris\/2016\/160626JVAlcHc.jpg\" alt=\"\" width=\"369\" height=\"133\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joan Vinyes, al volante de un Seat Le\u00f3n preparado por Baporo Motorsport, estar\u00e1 en la pista de las instalaciones de Motorland para disputar las pruebas del Campeonato de Espa\u00f1a de Resistencia programadas en el tercer meeting del calendario 2016 del mencionado certamen. En la cita de Alca\u00f1iz, Vinyes compartir\u00e1 el volante del Le\u00f3n con Marc Carol.   <\/p>\n","protected":false},"author":1,"featured_media":1686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[52,92],"tags":[],"class_list":["post-2441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-circuitos","category-circuitos-espana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motorland el escenario escogido por Joan Vinyes para volver a competir - Equip vinyes dabad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motorland el escenario escogido por Joan Vinyes para volver a competir - Equip vinyes dabad\" \/>\n<meta property=\"og:description\" content=\"Joan Vinyes, al volante de un Seat Le\u00f3n preparado por Baporo Motorsport, estar\u00e1 en la pista de las instalaciones de Motorland para disputar las pruebas del Campeonato de Espa\u00f1a de Resistencia programadas en el tercer meeting del calendario 2016 del mencionado certamen. En la cita de Alca\u00f1iz, Vinyes compartir\u00e1 el volante del Le\u00f3n con Marc Carol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/\" \/>\n<meta property=\"og:site_name\" content=\"Equip vinyes dabad\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-21T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T20:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2024\/10\/logo_vinyes_dabad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"130\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#\\\/schema\\\/person\\\/962b4c681d63fd4fbd546ec83b775c1b\"},\"headline\":\"Motorland el escenario escogido por Joan Vinyes para volver a competir\",\"datePublished\":\"2016-06-21T00:00:00+00:00\",\"dateModified\":\"2024-10-31T20:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/\"},\"wordCount\":490,\"image\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equipvinyesdabad.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/13JVAlc0092.jpg\",\"articleSection\":[\"Circuitos\",\"Circuitos Espa\u00f1a\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/\",\"url\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/\",\"name\":\"Motorland el escenario escogido por Joan Vinyes para volver a competir - Equip vinyes dabad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equipvinyesdabad.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/13JVAlc0092.jpg\",\"datePublished\":\"2016-06-21T00:00:00+00:00\",\"dateModified\":\"2024-10-31T20:22:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#\\\/schema\\\/person\\\/962b4c681d63fd4fbd546ec83b775c1b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equipvinyesdabad.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/13JVAlc0092.jpg\",\"contentUrl\":\"https:\\\/\\\/equipvinyesdabad.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/13JVAlc0092.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/circuitos\\\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motorland el escenario escogido por Joan Vinyes para volver a competir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/\",\"name\":\"Equip vinyes dabad\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/#\\\/schema\\\/person\\\/962b4c681d63fd4fbd546ec83b775c1b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/equipvinyesdabad.com\"],\"url\":\"https:\\\/\\\/equipvinyesdabad.com\\\/es\\\/author\\\/web1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motorland el escenario escogido por Joan Vinyes para volver a competir - Equip vinyes dabad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/","og_locale":"es_ES","og_type":"article","og_title":"Motorland el escenario escogido por Joan Vinyes para volver a competir - Equip vinyes dabad","og_description":"Joan Vinyes, al volante de un Seat Le\u00f3n preparado por Baporo Motorsport, estar\u00e1 en la pista de las instalaciones de Motorland para disputar las pruebas del Campeonato de Espa\u00f1a de Resistencia programadas en el tercer meeting del calendario 2016 del mencionado certamen. En la cita de Alca\u00f1iz, Vinyes compartir\u00e1 el volante del Le\u00f3n con Marc Carol.","og_url":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/","og_site_name":"Equip vinyes dabad","article_published_time":"2016-06-21T00:00:00+00:00","article_modified_time":"2024-10-31T20:22:38+00:00","og_image":[{"width":250,"height":130,"url":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2024\/10\/logo_vinyes_dabad.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/#article","isPartOf":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/"},"author":{"name":"admin","@id":"https:\/\/equipvinyesdabad.com\/es\/#\/schema\/person\/962b4c681d63fd4fbd546ec83b775c1b"},"headline":"Motorland el escenario escogido por Joan Vinyes para volver a competir","datePublished":"2016-06-21T00:00:00+00:00","dateModified":"2024-10-31T20:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/"},"wordCount":490,"image":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/#primaryimage"},"thumbnailUrl":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2016\/06\/13JVAlc0092.jpg","articleSection":["Circuitos","Circuitos Espa\u00f1a"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/","url":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/","name":"Motorland el escenario escogido por Joan Vinyes para volver a competir - Equip vinyes dabad","isPartOf":{"@id":"https:\/\/equipvinyesdabad.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/#primaryimage"},"image":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/#primaryimage"},"thumbnailUrl":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2016\/06\/13JVAlc0092.jpg","datePublished":"2016-06-21T00:00:00+00:00","dateModified":"2024-10-31T20:22:38+00:00","author":{"@id":"https:\/\/equipvinyesdabad.com\/es\/#\/schema\/person\/962b4c681d63fd4fbd546ec83b775c1b"},"breadcrumb":{"@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/#primaryimage","url":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2016\/06\/13JVAlc0092.jpg","contentUrl":"https:\/\/equipvinyesdabad.com\/wp-content\/uploads\/2016\/06\/13JVAlc0092.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/equipvinyesdabad.com\/es\/circuitos\/motorland-el-escenario-escogido-por-joan-vinyes-para-volver-a-competir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/equipvinyesdabad.com\/es\/"},{"@type":"ListItem","position":2,"name":"Motorland el escenario escogido por Joan Vinyes para volver a competir"}]},{"@type":"WebSite","@id":"https:\/\/equipvinyesdabad.com\/es\/#website","url":"https:\/\/equipvinyesdabad.com\/es\/","name":"Equip vinyes dabad","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equipvinyesdabad.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/equipvinyesdabad.com\/es\/#\/schema\/person\/962b4c681d63fd4fbd546ec83b775c1b","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d1c6cfbf1c3aed75f7a05f946b76867c29d677b49f81545b6b9bc58677b08a0?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/equipvinyesdabad.com"],"url":"https:\/\/equipvinyesdabad.com\/es\/author\/web1\/"}]}},"_links":{"self":[{"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/posts\/2441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/comments?post=2441"}],"version-history":[{"count":3,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/posts\/2441\/revisions"}],"predecessor-version":[{"id":4566,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/posts\/2441\/revisions\/4566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/media\/1686"}],"wp:attachment":[{"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/media?parent=2441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/categories?post=2441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/equipvinyesdabad.com\/es\/wp-json\/wp\/v2\/tags?post=2441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}